{"id":929,"date":"2026-04-13T19:54:33","date_gmt":"2026-04-13T10:54:33","guid":{"rendered":"https:\/\/www.insta-g.online\/ikebukurosanga\/?p=929"},"modified":"2026-04-13T22:22:08","modified_gmt":"2026-04-13T13:22:08","slug":"3874342795871367927","status":"publish","type":"post","link":"https:\/\/www.insta-g.online\/ikebukurosanga\/929\/","title":{"rendered":"3874342795871367927"},"content":{"rendered":"<p>\u304a\u795d\u3044\u306b\u3001\u63a5\u5f85\u306b\u3001\u7279\u5225\u306a\u65e5\u306b\u30fc\u3002<br \/>\n\u6c17\u54c1\u6f02\u3046\u5b8c\u5168\u500b\u5ba4\u306e\u7a7a\u9593\u3067\u7d20\u6575\u306a\u6642\u9593\u3092\u3002<br \/>\n\u8d05\u6ca2\u306a\u3072\u3068\u6642\u3092\u3001\u305c\u3072SANGA\u3067\u3002<br \/>\n\u3000<\/p>\n<p>\u5168\u5e2d\u55ab\u7159\u53ef\u80fd<br \/>\n\u203b\u30ab\u30a6\u30f3\u30bf\u30fc\u5e2d\u306f\u96fb\u5b50\u30bf\u30d0\u30b3\u306e\u307f<\/p>\n<p>\u273c\u2022\u2022\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2022\u2022\u273c<\/p>\n<p>\u3010\u524d\u83dc\u3011<br \/>\n\u86cd\u70cf\u8cca\u3000\u3046\u308b\u3044\u3000\u9162\u5473\u564c\u548c<\/p>\n<p>\u3010\u5fa1\u6900\u3011<br \/>\n\u685c\u6d77\u8001\u771f\u4e08\u3000\u3046\u3059\u3044\u8c46\u64e6\u308a\u6d41\u3057\t<\/p>\n<p>\u3010\u9020\u91cc\u3011<br \/>\n\u9c06\u3000\u521d\u9c39\t<\/p>\n<p>\u3010\u713c\u7269\u3011<br \/>\n\u685c\u9bdb\u3000\u30ec\u30e2\u30f3\u30d0\u30bf\u30fc\u713c<br \/>\n\u7518\u9162\u8317\u8377\u3000\u91d1\u67d1\u871c\u716e\u3000\t<\/p>\n<p>\u3010\u7bb8\u4f11\u3081\u3011<br \/>\n\u7261\u8823\u3000\u7b4d\u3000\u542b\u3081\u716e\t<\/p>\n<p>\u3010\u5f37\u80b4\u3011<br \/>\n\u548c\u725b\u30d2\u30ec\u3000\u65b0\u7389\u8471\u30bd\u30fc\u30b9\t<\/p>\n<p>\u3010\u5fa1\u98df\u4e8b\u3011<br \/>\n\u685c\u9bdb\u3000\u6728\u8033\u3000\u708a\u304d\u8fbc\u5fa1\u98ef<br \/>\n\u9999\u7269\u3000\u8d64\u51fa\u6c41<br \/>\n\u3000<br \/>\n\u3010\u6c34\u83d3\u5b50\u3011<br \/>\n\u767d\u7389\u30af\u30ea\u30fc\u30e0\u3042\u3093\u307f\u3064<\/p>\n<p>\u273c\u2022\u2022\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2022\u2022\u273c <\/p>\n<p>\u203b\u4ed5\u5165\u308c\u72b6\u6cc1\u306b\u3088\u308a\u5185\u5bb9\u304c\u5909\u66f4\u306b\u306a\u308b\u5834\u5408\u304c<br \/>\n\u3054\u3056\u3044\u307e\u3059\u3002\u3042\u3089\u304b\u3058\u3081\u3054\u4e86\u627f\u4e0b\u3055\u3044\u3002<\/p>\n<p>\ud83d\udccd\u6c60\u888bSANGA<\/p>\n<p>\u25a0\u30a2\u30af\u30bb\u30b9\uff1a\u300c\u6c60\u888b\u99c5\u300dC6\u51fa\u53e3\u304b\u3089\u5f92\u6b692\u5206<br \/>\n\u25a0\u5834\u6240\uff1a\u6771\u4eac\u90fd\u8c4a\u5cf6\u533a\u6c60\u888b2-40-14 B1F<br \/>\n\u25a0\u5e2d\u6570\uff1a\u30ab\u30a6\u30f3\u30bf\u30fc6\u5e2d\u30fb\u500b\u5ba43\u5ba4<br \/>\n\u25a0\u55b6\u696d\u6642\u9593\uff1a18:00-23:00<br \/>\n\u25a0\u5b9a\u4f11\u65e5\uff1a\u65e5\u66dc\u65e5\u30fb\u795d\u65e5<br \/>\n\u3000<br \/>\n\uff0d\uff0d\uff0d\uff0d\uff0d\uff0d\uff0d\uff0d\uff0d\uff0d\uff0d\uff0d\uff0d\uff0d\uff0d\uff0d\uff0d<\/p>\n<p>#\u6c60\u888bSANGA<br \/>\n#\u6c60\u888b\u30b5\u30f3\u30ac<br \/>\n#\u6c60\u888b\u3055\u3093\u304c<br \/>\n#SANGA\u6c60\u888b<br \/>\n#\u30b5\u30f3\u30ac\u6c60\u888b<br \/>\n\u3055\u3093\u304c\u6c60\u888b<br \/>\nSANGA<br \/>\n\u30b5\u30f3\u30ac<br \/>\n\u3055\u3093\u304c<br \/>\n\u6c60\u888b\u548c\u98df<br \/>\n\u6c60\u888b\u500b\u5ba4<br \/>\n\u6c60\u888b\u30d3\u30b9\u30c8\u30ed<br \/>\n\u6c60\u888b\u500b\u5ba4\u548c\u98df<br \/>\n\u6c60\u888b\u30c7\u30a3\u30ca\u30fc<br \/>\n\u8a18\u5ff5\u65e5<br \/>\n\u63a5\u5f85<br \/>\n\u4f1a\u98df<br \/>\n\u5b8c\u5168\u500b\u5ba4<br \/>\n\u6c60\u888b<br \/>\n\u548c\u98df<br \/>\n\u65e5\u672c\u9152<br \/>\n\u500b\u5ba4<br \/>\n\u55ab\u7159\u53ef<br \/>\n\u7d19\u30bf\u30d0\u30b3<br \/>\n\u7d19\u7159\u8349<br \/>\n\u7d19\u305f\u3070\u3053<br \/>\n\u30bf\u30d0\u30b3<br \/>\n\u305f\u3070\u3053<br \/>\n\u7159\u8349<br \/>\n\u96fb\u5b50\u30bf\u30d0\u30b3<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u304a\u795d\u3044\u306b\u3001\u63a5\u5f85\u306b\u3001\u7279\u5225\u306a\u65e5\u306b\u30fc\u3002 \u6c17\u54c1\u6f02\u3046\u5b8c\u5168\u500b\u5ba4\u306e\u7a7a\u9593\u3067\u7d20\u6575\u306a\u6642\u9593\u3092\u3002 \u8d05\u6ca2\u306a\u3072\u3068\u6642\u3092\u3001\u305c\u3072SANGA\u3067\u3002 \u3000 \u5168\u5e2d\u55ab\u7159\u53ef\u80fd \u203b\u30ab\u30a6\u30f3\u30bf\u30fc\u5e2d\u306f\u96fb\u5b50\u30bf\u30d0\u30b3\u306e\u307f \u273c\u2022\u2022\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2508\u2022\u2022\u273c \u3010\u524d\u83dc\u3011 \u86cd\u70cf\u8cca\u3000\u3046\u308b\u3044&hellip; <a class=\"more-link\" href=\"https:\/\/www.insta-g.online\/ikebukurosanga\/929\/\">\u7d9a\u304d\u3092\u8aad\u3080 <span class=\"screen-reader-text\">3874342795871367927<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":928,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","entry"],"_links":{"self":[{"href":"https:\/\/www.insta-g.online\/ikebukurosanga\/wp-json\/wp\/v2\/posts\/929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.insta-g.online\/ikebukurosanga\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.insta-g.online\/ikebukurosanga\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.insta-g.online\/ikebukurosanga\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.insta-g.online\/ikebukurosanga\/wp-json\/wp\/v2\/comments?post=929"}],"version-history":[{"count":1,"href":"https:\/\/www.insta-g.online\/ikebukurosanga\/wp-json\/wp\/v2\/posts\/929\/revisions"}],"predecessor-version":[{"id":930,"href":"https:\/\/www.insta-g.online\/ikebukurosanga\/wp-json\/wp\/v2\/posts\/929\/revisions\/930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.insta-g.online\/ikebukurosanga\/wp-json\/wp\/v2\/media\/928"}],"wp:attachment":[{"href":"https:\/\/www.insta-g.online\/ikebukurosanga\/wp-json\/wp\/v2\/media?parent=929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.insta-g.online\/ikebukurosanga\/wp-json\/wp\/v2\/categories?post=929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.insta-g.online\/ikebukurosanga\/wp-json\/wp\/v2\/tags?post=929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}